{"id":2491,"date":"2025-04-14T04:43:13","date_gmt":"2025-04-14T00:43:13","guid":{"rendered":"https:\/\/harmonie.kiimmo.com\/politique-en-matiere-de-confidentialite-et-de-cookies\/"},"modified":"2025-11-16T04:19:05","modified_gmt":"2025-11-16T00:19:05","slug":"politique-en-matiere-de-confidentialite-et-de-cookies","status":"publish","type":"page","link":"https:\/\/harmonie.kiimmo.com\/fr\/politique-en-matiere-de-confidentialite-et-de-cookies\/","title":{"rendered":"Politique en mati\u00e8re de confidentialit\u00e9 et de cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2491\" class=\"elementor elementor-2491 elementor-926\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a61e02 cookie e-flex e-con-boxed e-con e-parent\" data-id=\"7a61e02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d661f8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6d661f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique en mati\u00e8re de cookies\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbcf419 animated-slow elementor-invisible elementor-widget elementor-widget-n-accordion\" data-id=\"dbcf419\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2300\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2300\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qu'est-ce qu'un cookie? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2300\" class=\"elementor-element elementor-element-23bc5b2 e-con-full e-flex e-con e-child\" data-id=\"23bc5b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac04a6a elementor-widget elementor-widget-text-editor\" data-id=\"ac04a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa pr\u00e9sente politique en mati\u00e8re de cookies explique ce que sont les cookies et comment nous les utilisons, les types de cookies que nous utilisons, c&rsquo;est-\u00e0-dire les informations que nous recueillons \u00e0 l&rsquo;aide des cookies et la mani\u00e8re dont ces informations sont utilis\u00e9es, ainsi que la mani\u00e8re de g\u00e9rer les param\u00e8tres des cookies.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e1edb elementor-widget elementor-widget-text-editor\" data-id=\"56e1edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes cookies sont de petits fichiers texte utilis\u00e9s pour stocker de petits \u00e9l\u00e9ments d&rsquo;information. Ils sont stock\u00e9s sur votre appareil lorsque le site web est charg\u00e9 sur votre navigateur. Ces cookies nous aident \u00e0 faire fonctionner le site web correctement, \u00e0 le rendre plus s\u00fbr, \u00e0 offrir une meilleure exp\u00e9rience \u00e0 l&rsquo;utilisateur, \u00e0 comprendre comment le site web fonctionne et \u00e0 analyser ce qui fonctionne et ce qui doit \u00eatre am\u00e9lior\u00e9.  \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2301\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2301\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment utilisons-nous les cookies ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2301\" class=\"elementor-element elementor-element-462d837 e-con-full e-flex e-con e-child\" data-id=\"462d837\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b859b3 elementor-widget elementor-widget-text-editor\" data-id=\"8b859b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tComme la plupart des services en ligne, notre site web utilise des cookies de premi\u00e8re partie et de tierce partie \u00e0 plusieurs fins. Les cookies de premi\u00e8re partie sont essentiellement n\u00e9cessaires au bon fonctionnement du site web et ne collectent aucune de vos donn\u00e9es personnelles identifiables. \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ec9eb2 elementor-widget elementor-widget-text-editor\" data-id=\"5ec9eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes cookies tiers utilis\u00e9s sur notre site web servent principalement \u00e0 comprendre comment le site web fonctionne, comment vous interagissez avec notre site web, \u00e0 assurer la s\u00e9curit\u00e9 de nos services, \u00e0 fournir des publicit\u00e9s pertinentes pour vous et, dans l&rsquo;ensemble, \u00e0 vous offrir une exp\u00e9rience utilisateur meilleure et am\u00e9lior\u00e9e et \u00e0 acc\u00e9l\u00e9rer vos interactions futures avec notre site web.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2302\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2302\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Types de cookies que nous utilisons <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2302\" class=\"elementor-element elementor-element-00a367a e-con-full e-flex e-con e-child\" data-id=\"00a367a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bee8c9c elementor-widget elementor-widget-html\" data-id=\"bee8c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cky-audit-table-element\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38aae70 elementor-widget elementor-widget-text-editor\" data-id=\"38aae70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVous pouvez modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies \u00e0 tout moment en cliquant sur le bouton ci-dessus. Cela vous permettra de revenir \u00e0 la banni\u00e8re de consentement aux cookies et de modifier vos pr\u00e9f\u00e9rences ou de retirer votre consentement imm\u00e9diatement. \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-763875e elementor-widget elementor-widget-text-editor\" data-id=\"763875e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEn outre, les navigateurs proposent des m\u00e9thodes diff\u00e9rentes pour bloquer et supprimer les cookies utilis\u00e9s par les sites web. Vous pouvez modifier les param\u00e8tres de votre navigateur pour bloquer\/supprimer les cookies. Vous trouverez ci-dessous les liens vers les documents d&rsquo;assistance relatifs \u00e0 la gestion et \u00e0 la suppression des cookies des principaux navigateurs web.  \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c70d1b1 fix-links elementor-widget elementor-widget-text-editor\" data-id=\"c70d1b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chrome<a href=\"https:\/\/support.google.com\/accounts\/answer\/32050\" target=\"_blank\" rel=\"noopener\">: https:\/\/support.google.com\/accounts\/answer\/32050<\/a><\/p><p>Safari <a href=\"https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac\" target=\"_blank\" rel=\"noopener\">: https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac<\/a><\/p><p>Firefox <a href=\"https:\/\/support.mozilla.org\/en-US\/kb\/clear-cookies-and-site-data-firefox?redirectslug=delete-cookies-remove-info-websites-stored&amp;redirectlocale=en-US\" target=\"_blank\" rel=\"noopener\">: https:\/\/support.mozilla.org\/en-US\/kb\/clear-cookies-and-site-data-firefox?redirectslug=delete-cookies-remove-info-websites-stored&amp;redirectlocale=en-US<\/a><\/p><p>Internet Explorer <a href=\"https:\/\/support.microsoft.com\/en-us\/topic\/how-to-delete-cookie-files-in-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc\" target=\"_blank\" rel=\"noopener\">: https:\/\/support.microsoft.com\/en-us\/topic\/how-to-delete-cookie-files-in-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad635b elementor-widget elementor-widget-text-editor\" data-id=\"6ad635b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous utilisez un autre navigateur web, veuillez consulter les documents d&rsquo;assistance officiels de votre navigateur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29da354 e-flex e-con-boxed e-con e-parent\" data-id=\"29da354\" data-element_type=\"container\" data-e-type=\"container\" id=\"privacy\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-263262d animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"263262d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e75a61 e-con-full e-flex e-con e-child\" data-id=\"8e75a61\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a72ee15 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a72ee15\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette politique de confidentialit\u00e9 d\u00e9crit les politiques de KI&rsquo;IMMO Ltd, Turbine, Vivea Business Park, Moka, Mauritius, Email : contact@kiimmo.com, Phone : +230 5944 4417 sur la collecte, l&rsquo;utilisation et la divulgation des informations que nous recueillons lorsque vous utilisez notre site web ( https:\/\/harmonie.kiimmo.com ). (le \u00ab\u00a0Service\u00a0\u00bb). En acc\u00e9dant au service ou en l&rsquo;utilisant, vous consentez \u00e0 la collecte, \u00e0 l&rsquo;utilisation et \u00e0 la divulgation de vos informations conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9. Si vous n&rsquo;y consentez pas, veuillez ne pas acc\u00e9der au service ni l&rsquo;utiliser.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b84e7a7 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b84e7a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous pouvons modifier la pr\u00e9sente politique de confidentialit\u00e9 \u00e0 tout moment sans vous en informer au pr\u00e9alable et nous publierons la politique de confidentialit\u00e9 r\u00e9vis\u00e9e sur le service. La politique r\u00e9vis\u00e9e entrera en vigueur 180 jours apr\u00e8s sa publication sur le service et votre acc\u00e8s ou utilisation continue du service apr\u00e8s cette date constituera votre acceptation de la politique de confidentialit\u00e9 r\u00e9vis\u00e9e. Nous vous recommandons donc de consulter r\u00e9guli\u00e8rement cette page.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4e565 animated-slow elementor-invisible elementor-widget elementor-widget-n-accordion\" data-id=\"ae4e565\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1820\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1820\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Informations que nous recueillons <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1820\" class=\"elementor-element elementor-element-fb93be5 e-con-full e-flex e-con e-child\" data-id=\"fb93be5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6e6956 elementor-widget elementor-widget-text-editor\" data-id=\"e6e6956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"privacy-policy-p\">Nous collecterons et traiterons les informations personnelles suivantes vous concernant :<br><br><\/p><ol><li>Nom<\/li><li>Courriel<\/li><li>Mobile<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1821\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1821\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment nous utilisons vos informations <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1821\" class=\"elementor-element elementor-element-36620e5 e-con-full e-flex e-con e-child\" data-id=\"36620e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51e9d10 elementor-widget elementor-widget-text-editor\" data-id=\"51e9d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous utiliserons les informations que nous recueillons \u00e0 votre sujet aux fins suivantes :\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50087e6 elementor-widget elementor-widget-text-editor\" data-id=\"50087e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol class=\"privacy-policy-ol\"><li>Marketing\/ Promotion<\/li><li>Informations sur l&rsquo;administration<\/li><li>Publicit\u00e9 cibl\u00e9e<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-490cb29 elementor-widget elementor-widget-text-editor\" data-id=\"490cb29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSi nous voulons utiliser vos informations \u00e0 d&rsquo;autres fins, nous vous demanderons votre consentement et nous n&rsquo;utiliserons vos informations qu&rsquo;apr\u00e8s avoir re\u00e7u votre consentement et, dans ce cas, uniquement aux fins pour lesquelles vous avez donn\u00e9 votre consentement, sauf si la loi nous oblige \u00e0 faire autrement.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1822\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1822\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment nous partageons vos informations <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1822\" class=\"elementor-element elementor-element-21f0027 e-con-full e-flex e-con e-child\" data-id=\"21f0027\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46b8fe5 elementor-widget elementor-widget-text-editor\" data-id=\"46b8fe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous ne transf\u00e9rerons pas vos informations personnelles \u00e0 un tiers sans votre consentement, sauf dans les circonstances limit\u00e9es d\u00e9crites ci-dessous :\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-310d0ea elementor-widget elementor-widget-text-editor\" data-id=\"310d0ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol class=\"privacy-policy-ol\"><li>Service de publicit\u00e9<\/li><li>Analyse<\/li><li>Collecte et traitement des donn\u00e9es<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25c858a fix-links elementor-widget elementor-widget-text-editor\" data-id=\"25c858a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous demandons \u00e0 ces tiers d&rsquo;utiliser les informations personnelles que nous leur transf\u00e9rons uniquement aux fins pour lesquelles elles ont \u00e9t\u00e9 transf\u00e9r\u00e9es et de ne pas les conserver plus longtemps qu&rsquo;il n&rsquo;est n\u00e9cessaire pour atteindre lesdites fins.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81f21d2 elementor-widget elementor-widget-text-editor\" data-id=\"81f21d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous pouvons \u00e9galement divulguer vos informations personnelles dans les cas suivants : (1) se conformer \u00e0 la loi, \u00e0 la r\u00e9glementation, \u00e0 l&rsquo;ordonnance d&rsquo;un tribunal ou \u00e0 toute autre proc\u00e9dure judiciaire applicable ; (2) faire respecter les accords que vous avez conclus avec nous, y compris la pr\u00e9sente politique de confidentialit\u00e9 ; ou (3) r\u00e9pondre \u00e0 des r\u00e9clamations selon lesquelles votre utilisation du service viole les droits d&rsquo;une tierce partie. Si le service ou notre soci\u00e9t\u00e9 est fusionn\u00e9 ou acquis par une autre soci\u00e9t\u00e9, vos informations seront l&rsquo;un des actifs transf\u00e9r\u00e9s au nouveau propri\u00e9taire. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1823\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1823\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Conservation de vos informations <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1823\" class=\"elementor-element elementor-element-b6fcaa2 e-con-full e-flex e-con e-child\" data-id=\"b6fcaa2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0955ec7 elementor-widget elementor-widget-text-editor\" data-id=\"0955ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous conserverons vos informations personnelles pendant 90 jours \u00e0 2 ans apr\u00e8s que les utilisateurs ont r\u00e9sili\u00e9 leur compte ou aussi longtemps que nous en aurons besoin pour atteindre les objectifs pour lesquels elles ont \u00e9t\u00e9 collect\u00e9es, comme indiqu\u00e9 dans la pr\u00e9sente politique de protection de la vie priv\u00e9e. Il se peut que nous devions conserver certaines informations pour des p\u00e9riodes plus longues, par exemple pour la tenue de registres ou l&rsquo;\u00e9tablissement de rapports conform\u00e9ment \u00e0 la l\u00e9gislation applicable ou pour d&rsquo;autres raisons l\u00e9gitimes telles que l&rsquo;application de droits l\u00e9gaux, la pr\u00e9vention de la fraude, etc. Les informations anonymes r\u00e9siduelles et les informations agr\u00e9g\u00e9es, qui ne permettent pas de vous identifier (directement ou indirectement), peuvent \u00eatre stock\u00e9es ind\u00e9finiment.  \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1824\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1824\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Vos droits <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1824\" class=\"elementor-element elementor-element-e4327ab e-con-full e-flex e-con e-child\" data-id=\"e4327ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9819ca elementor-widget elementor-widget-text-editor\" data-id=\"b9819ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En fonction de la l\u00e9gislation applicable, vous pouvez avoir un droit d&rsquo;acc\u00e8s et de rectification ou d&rsquo;effacement de vos donn\u00e9es \u00e0 caract\u00e8re personnel ou recevoir une copie de vos donn\u00e9es \u00e0 caract\u00e8re personnel, restreindre le traitement actif de vos donn\u00e9es ou vous y opposer, nous demander de partager (portage) vos donn\u00e9es \u00e0 caract\u00e8re personnel avec une autre entit\u00e9, retirer tout consentement que vous nous avez donn\u00e9 pour traiter vos donn\u00e9es, un droit de d\u00e9poser une plainte aupr\u00e8s d&rsquo;une autorit\u00e9 statutaire et tout autre droit pertinent en vertu de la l\u00e9gislation applicable. Pour exercer ces droits, vous pouvez nous \u00e9crire \u00e0 contact@kiimmo.com. Nous r\u00e9pondrons \u00e0 votre demande conform\u00e9ment \u00e0 la l\u00e9gislation applicable.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2467def elementor-widget elementor-widget-text-editor\" data-id=\"2467def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVeuillez noter que si vous ne nous autorisez pas \u00e0 collecter ou \u00e0 traiter les informations personnelles requises ou si vous retirez votre consentement au traitement de ces informations aux fins requises, il se peut que vous ne puissiez pas acc\u00e9der aux services pour lesquels vos informations ont \u00e9t\u00e9 demand\u00e9es, ni les utiliser.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1825\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1825\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cookies Etc <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1825\" class=\"elementor-element elementor-element-54bc759 e-con-full e-flex e-con e-child\" data-id=\"54bc759\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e48f4f elementor-widget elementor-widget-text-editor\" data-id=\"0e48f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPour en savoir plus sur la mani\u00e8re dont nous utilisons ces technologies et sur les choix qui s&rsquo;offrent \u00e0 vous en ce qui concerne ces technologies de suivi, veuillez consulter notre politique en mati\u00e8re de cookies.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1826\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1826\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> S\u00e9curit\u00e9 <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1826\" class=\"elementor-element elementor-element-bfc529c e-con-full e-flex e-con e-child\" data-id=\"bfc529c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10a8754 elementor-widget elementor-widget-text-editor\" data-id=\"10a8754\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa s\u00e9curit\u00e9 de vos informations est importante pour nous et nous utiliserons des mesures de s\u00e9curit\u00e9 raisonnables pour emp\u00eacher la perte, l&rsquo;utilisation abusive ou la modification non autoris\u00e9e de vos informations sous notre contr\u00f4le. Toutefois, compte tenu des risques inh\u00e9rents, nous ne pouvons pas garantir une s\u00e9curit\u00e9 absolue et, par cons\u00e9quent, nous ne pouvons pas assurer ou garantir la s\u00e9curit\u00e9 des informations que vous nous transmettez et vous le faites \u00e0 vos propres risques. \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1827\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1827\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> D\u00e9l\u00e9gu\u00e9 aux griefs \/ \u00e0 la protection des donn\u00e9es <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1827\" class=\"elementor-element elementor-element-96e33e7 e-con-full e-flex e-con e-child\" data-id=\"96e33e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be77a67 elementor-widget elementor-widget-text-editor\" data-id=\"be77a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous avez des questions ou des pr\u00e9occupations concernant le traitement de vos informations disponibles chez nous, vous pouvez envoyer un courriel \u00e0 notre Grievance Officer \u00e0 KI&rsquo;IMMO Ltd, Turbine, Vivea Business Park, Moka, Mauritius, Courriel : contact@kiimmo.com, T\u00e9l\u00e9phone : +230 5944 4417 : +230 5944 4417. Nous r\u00e9pondrons \u00e0 vos pr\u00e9occupations conform\u00e9ment \u00e0 la l\u00e9gislation applicable. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique en mati\u00e8re de cookies Qu&rsquo;est-ce qu&rsquo;un cookie? La pr\u00e9sente politique en mati\u00e8re de cookies explique ce que sont les cookies et comment nous les utilisons, les types de cookies que nous utilisons, c&#8217;est-\u00e0-dire les informations que nous recueillons \u00e0 l&#8217;aide des cookies et la mani\u00e8re dont ces informations sont utilis\u00e9es, ainsi que la mani\u00e8re [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2491","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/pages\/2491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":0,"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/pages\/2491\/revisions"}],"wp:attachment":[{"href":"https:\/\/harmonie.kiimmo.com\/fr\/wp-json\/wp\/v2\/media?parent=2491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}